{"id":2047,"date":"2025-06-03T22:02:57","date_gmt":"2025-06-03T22:02:57","guid":{"rendered":"https:\/\/acedijusrs.com.br\/2024\/?p=2047"},"modified":"2025-06-03T22:02:57","modified_gmt":"2025-06-03T22:02:57","slug":"acedijus-rs-insiste-em-pleitos-fundamentais-a-categoria-em-especial-aos-inativos","status":"publish","type":"post","link":"https:\/\/acedijusrs.com.br\/2024\/2025\/06\/03\/acedijus-rs-insiste-em-pleitos-fundamentais-a-categoria-em-especial-aos-inativos\/","title":{"rendered":"ACEDIJUS RS insiste em pleitos fundamentais \u00e0 categoria, em especial aos inativos"},"content":{"rendered":"\n<p>Nesta segunda-feira, 02, atrav\u00e9s de novo of\u00edcio dirigido ao Presidente do Tribunal de Justi\u00e7a do Rio Grande do Sul, a ACEDIJUS RS reiterou pedido de pagamento da primeira parcela da Gratifica\u00e7\u00e3o Natalina para julho pr\u00f3ximo, a exemplo do que ocorreu no ano passado, bem como insistiu no pleito relatico ao Aux\u00edlio Social \u00e0 ordem de um valor ison\u00f4mico ao do Aux\u00edlio Alimenta\u00e7\u00e3o, esse o mais justo e razo\u00e1vel para sanar de vez a defasagem de vencimentos em rela\u00e7\u00e3o aos servidores da ativa, sendo que qualquer outro valor aqu\u00e9m que venha a ser ofertado \u00e9 insatisfat\u00f3rio e absolutamente insuficiente para transpor minimamente as dificuldades enfrentadas pelo segmento, desde que sucessivas mudan\u00e7as na legisla\u00e7\u00e3o v\u00eam impondo cada vez maiores sacr\u00edficios \u00e0queles que deram a maior parte do tempo de suas vidas a servi\u00e7o do Poder Judici\u00e1rio.<\/p>\n\n\n\n<p>O presidente reeleito da entidade, Analista Judici\u00e1rio, Marco Aurelio Ricciardi Weber, que em seu discurso de posse manifestou &#8220;contrariedade em rela\u00e7\u00e3o ao silencio e ao abandono que o TJRS dedicou aos servidores atingidos pelas enchentes do ano passado, alcan\u00e7ando apenas &#8220;meia por\u00e7\u00e3o&#8221; de uma gratifica\u00e7\u00e3o natalina que ao final do ano foi dizimada pelo Imposto de Renda, enquanto a entidade, em voz solit\u00e1ria, atrav\u00e9s de in\u00fameras solicita\u00e7\u00f5es, inclusive com o apoio da AJURIS, &#8220;suplicava&#8221; por um aux\u00edlio emergencial poss\u00edvel e \u00e0 ordem de um vencimento l\u00edquido, s\u00f3 o sil\u00eancio teve como resposta. Posteriormente, atrav\u00e9s do projeto de revis\u00e3o do Plano de Cargos e Sal\u00e1rios, que ainda pende de aprova\u00e7\u00e3o pelo Legislativo, houve avan\u00e7os, fa\u00e7a-se justi\u00e7a&#8221;, agora espera medidas contundentes e voltadas a solucionar esse grave v\u00e1cuo existente na vida desses pessoas. &#8220;Institui\u00e7\u00f5es s\u00e3o as pessoas que as fazem funcionar, sem as pessoas, viram meros entes abstratos, sem valor e sem capacidade de atua\u00e7\u00e3o&#8221;, arrematou.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/acedijusrs.com.br\/2024\/wp-content\/uploads\/2025\/06\/unnamed-2.png\" alt=\"\" class=\"wp-image-2048\" style=\"width:247px;height:auto\" srcset=\"https:\/\/acedijusrs.com.br\/2024\/wp-content\/uploads\/2025\/06\/unnamed-2.png 360w, https:\/\/acedijusrs.com.br\/2024\/wp-content\/uploads\/2025\/06\/unnamed-2-300x300.png 300w, https:\/\/acedijusrs.com.br\/2024\/wp-content\/uploads\/2025\/06\/unnamed-2-150x150.png 150w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption class=\"wp-element-caption\">Weber demonstrou seu desapontamento quanto ao desatendimento, pelo TJRS, ao pleito de aux\u00edlio emergencial aos atingidos pelas enchentes do ano passado.<\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nesta segunda-feira, 02, atrav\u00e9s de novo of\u00edcio dirigido ao Presidente do Tribunal de Justi\u00e7a do Rio Grande do Sul, a ACEDIJUS RS reiterou pedido de pagamento da primeira parcela da Gratifica\u00e7\u00e3o Natalina para julho pr\u00f3ximo, a exemplo do que ocorreu no ano passado, bem como insistiu no pleito relatico ao<a href=\"https:\/\/acedijusrs.com.br\/2024\/2025\/06\/03\/acedijus-rs-insiste-em-pleitos-fundamentais-a-categoria-em-especial-aos-inativos\/\" class=\"read-more\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2047","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/posts\/2047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/comments?post=2047"}],"version-history":[{"count":1,"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/posts\/2047\/revisions"}],"predecessor-version":[{"id":2049,"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/posts\/2047\/revisions\/2049"}],"wp:attachment":[{"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/media?parent=2047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/categories?post=2047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acedijusrs.com.br\/2024\/wp-json\/wp\/v2\/tags?post=2047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}